{"id":16201,"date":"2024-05-30T12:03:54","date_gmt":"2024-05-30T10:03:54","guid":{"rendered":"https:\/\/www.medes.fr\/?p=16201"},"modified":"2024-06-18T16:59:59","modified_gmt":"2024-06-18T14:59:59","slug":"journee-espace-et-sante","status":"publish","type":"post","link":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/","title":{"rendered":"Journ\u00e9e Espace et Sport"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><em><span class=\"break-words       tvm-parent-container\"><span dir=\"ltr\">26 mai 2024<\/span><\/span><\/em><\/p>\n<p><span class=\"break-words       tvm-parent-container\"><span dir=\"ltr\">Nous sommes ravis d&#8217;avoir pris part \u00e0 la journ\u00e9e in\u00e9dite organis\u00e9e \u00e0 la Cit\u00e9 de l&#8217;espace le 26 mai dernier sous le signe de l\u2019espace et du sport. L&#8217;occasion de montrer les similitudes qui existent entre le milieu du sport et le milieu du spatial, notamment celui des astronautes \ud83d\udc69\u200d\ud83d\ude80, que ce soit pour l\u2019entra\u00eenement physique, la pr\u00e9paration mentale ou l\u2019esprit d\u2019\u00e9quipe.<span class=\"white-space-pre\"> <\/span><span><br \/><\/span>Nos intervenants<span class=\"white-space-pre\"> <\/span><a class=\"app-aware-link \" target=\"_self\" href=\"https:\/\/www.linkedin.com\/company\/medes---institute-for-space-medicine-and-physiology\/\" data-test-app-aware-link=\"\" rel=\"noopener\"><span><\/span><\/a><span> MEDES <\/span>se sont joints aux moments d&#8217;\u00e9changes organis\u00e9s par la Cit\u00e9 et ont fait part de leur exp\u00e9rience, en tant que m\u00e9decin des astronautes et volontaire de l&#8217;\u00e9tude d&#8217;alitement de longue dur\u00e9e BRACE.<span class=\"white-space-pre\"> <\/span><span><br \/><\/span>\ud83d\ude4f Merci \u00e0 la Cit\u00e9 de l&#8217;espace pour l&#8217;invitation et pour cette superbe journ\u00e9e.<br \/><\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png&#8221; title_text=&#8221;Journ\u00e9e Espace et Sport&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/cde-espace-sport-1920&#215;1080-16-9.jpg&#8221; title_text=&#8221;cde-espace-sport-1920&#215;1080-16-9&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>26 mai 2024 Nous sommes ravis d&#8217;avoir pris part \u00e0 la journ\u00e9e in\u00e9dite organis\u00e9e \u00e0 la Cit\u00e9 de l&#8217;espace le 26 mai dernier sous le signe de l\u2019espace et du sport. L&#8217;occasion de montrer les similitudes qui existent entre le milieu du sport et le milieu du spatial, notamment celui des astronautes \ud83d\udc69\u200d\ud83d\ude80, que ce [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[5,19,1],"tags":[],"class_list":["post-16201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-actualites","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9e Espace et Sport - Medes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9e Espace et Sport - Medes\" \/>\n<meta property=\"og:description\" content=\"26 mai 2024 Nous sommes ravis d&#039;avoir pris part \u00e0 la journ\u00e9e in\u00e9dite organis\u00e9e \u00e0 la Cit\u00e9 de l&#039;espace le 26 mai dernier sous le signe de l\u2019espace et du sport. L&#039;occasion de montrer les similitudes qui existent entre le milieu du sport et le milieu du spatial, notamment celui des astronautes \ud83d\udc69\u200d\ud83d\ude80, que ce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Medes\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-30T10:03:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T14:59:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1333\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Medes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Medes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/\"},\"author\":{\"name\":\"Medes\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/#\\\/schema\\\/person\\\/d9d42a6448e34d220b88e51373fa8e55\"},\"headline\":\"Journ\u00e9e Espace et Sport\",\"datePublished\":\"2024-05-30T10:03:54+00:00\",\"dateModified\":\"2024-06-18T14:59:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/\"},\"wordCount\":316,\"image\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medes.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Journee-Espace-et-Sport.png\",\"articleSection\":[\"\u00e0 la une\",\"Actualit\u00e9s\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/\",\"url\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/\",\"name\":\"Journ\u00e9e Espace et Sport - Medes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medes.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Journee-Espace-et-Sport.png\",\"datePublished\":\"2024-05-30T10:03:54+00:00\",\"dateModified\":\"2024-06-18T14:59:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/#\\\/schema\\\/person\\\/d9d42a6448e34d220b88e51373fa8e55\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.medes.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Journee-Espace-et-Sport.png\",\"contentUrl\":\"https:\\\/\\\/www.medes.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Journee-Espace-et-Sport.png\",\"width\":1333,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/non-classifiee\\\/journee-espace-et-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/category\\\/uncategorized\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Journ\u00e9e Espace et Sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/\",\"name\":\"Medes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/#\\\/schema\\\/person\\\/d9d42a6448e34d220b88e51373fa8e55\",\"name\":\"Medes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94a3a44768861d4672a1ab6030b5709d468527f935bd404cd96410f423656e17?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94a3a44768861d4672a1ab6030b5709d468527f935bd404cd96410f423656e17?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94a3a44768861d4672a1ab6030b5709d468527f935bd404cd96410f423656e17?s=96&d=mm&r=g\",\"caption\":\"Medes\"},\"url\":\"https:\\\/\\\/www.medes.fr\\\/en\\\/author\\\/medes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9e Espace et Sport - Medes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/","og_locale":"en_US","og_type":"article","og_title":"Journ\u00e9e Espace et Sport - Medes","og_description":"26 mai 2024 Nous sommes ravis d'avoir pris part \u00e0 la journ\u00e9e in\u00e9dite organis\u00e9e \u00e0 la Cit\u00e9 de l'espace le 26 mai dernier sous le signe de l\u2019espace et du sport. L'occasion de montrer les similitudes qui existent entre le milieu du sport et le milieu du spatial, notamment celui des astronautes \ud83d\udc69\u200d\ud83d\ude80, que ce [&hellip;]","og_url":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/","og_site_name":"Medes","article_published_time":"2024-05-30T10:03:54+00:00","article_modified_time":"2024-06-18T14:59:59+00:00","og_image":[{"width":1333,"height":720,"url":"https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png","type":"image\/png"}],"author":"Medes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Medes","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#article","isPartOf":{"@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/"},"author":{"name":"Medes","@id":"https:\/\/www.medes.fr\/en\/#\/schema\/person\/d9d42a6448e34d220b88e51373fa8e55"},"headline":"Journ\u00e9e Espace et Sport","datePublished":"2024-05-30T10:03:54+00:00","dateModified":"2024-06-18T14:59:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/"},"wordCount":316,"image":{"@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png","articleSection":["\u00e0 la une","Actualit\u00e9s","Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/","url":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/","name":"Journ\u00e9e Espace et Sport - Medes","isPartOf":{"@id":"https:\/\/www.medes.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#primaryimage"},"image":{"@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png","datePublished":"2024-05-30T10:03:54+00:00","dateModified":"2024-06-18T14:59:59+00:00","author":{"@id":"https:\/\/www.medes.fr\/en\/#\/schema\/person\/d9d42a6448e34d220b88e51373fa8e55"},"breadcrumb":{"@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#primaryimage","url":"https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png","contentUrl":"https:\/\/www.medes.fr\/wp-content\/uploads\/2024\/06\/Journee-Espace-et-Sport.png","width":1333,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.medes.fr\/en\/non-classifiee\/journee-espace-et-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medes.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Uncategorized","item":"https:\/\/www.medes.fr\/en\/category\/uncategorized\/"},{"@type":"ListItem","position":3,"name":"Journ\u00e9e Espace et Sport"}]},{"@type":"WebSite","@id":"https:\/\/www.medes.fr\/en\/#website","url":"https:\/\/www.medes.fr\/en\/","name":"Medes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medes.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.medes.fr\/en\/#\/schema\/person\/d9d42a6448e34d220b88e51373fa8e55","name":"Medes","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/94a3a44768861d4672a1ab6030b5709d468527f935bd404cd96410f423656e17?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94a3a44768861d4672a1ab6030b5709d468527f935bd404cd96410f423656e17?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94a3a44768861d4672a1ab6030b5709d468527f935bd404cd96410f423656e17?s=96&d=mm&r=g","caption":"Medes"},"url":"https:\/\/www.medes.fr\/en\/author\/medes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/posts\/16201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/comments?post=16201"}],"version-history":[{"count":0,"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/posts\/16201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/media\/16204"}],"wp:attachment":[{"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/media?parent=16201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/categories?post=16201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medes.fr\/en\/wp-json\/wp\/v2\/tags?post=16201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}